{"id":103,"count":13,"description":"","link":"https:\/\/test2.bolderparis.com\/fr\/categorie-produit\/coques-de-telephone\/coques-transparentes\/zodiaque\/","name":"Zodiaque","slug":"zodiaque","taxonomy":"product_cat","parent":102,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zodiaque Archives - test2.bolderparis.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zodiaque Archives - test2.bolderparis.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/\" \/>\n<meta property=\"og:site_name\" content=\"test2.bolderparis.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/\",\"url\":\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/\",\"name\":\"Zodiaque Archives - test2.bolderparis.com\",\"isPartOf\":{\"@id\":\"https:\/\/test2.bolderparis.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/test2.bolderparis.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Phone cases\",\"item\":\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Clear cases\",\"item\":\"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Zodiac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test2.bolderparis.com\/#website\",\"url\":\"https:\/\/test2.bolderparis.com\/\",\"name\":\"test2.bolderparis.com\",\"description\":\"only cute people wear kasey\",\"publisher\":{\"@id\":\"https:\/\/test2.bolderparis.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test2.bolderparis.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/test2.bolderparis.com\/#organization\",\"name\":\"KASEY CASES\",\"url\":\"https:\/\/test2.bolderparis.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg\",\"contentUrl\":\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg\",\"width\":620,\"height\":357,\"caption\":\"KASEY CASES\"},\"image\":{\"@id\":\"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/kaseycases\/\",\"https:\/\/www.tiktok.com\/@kaseycases\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zodiaque Archives - test2.bolderparis.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/","og_locale":"fr_FR","og_type":"article","og_title":"Zodiaque Archives - test2.bolderparis.com","og_url":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/","og_site_name":"test2.bolderparis.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/","url":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/","name":"Zodiaque Archives - test2.bolderparis.com","isPartOf":{"@id":"https:\/\/test2.bolderparis.com\/#website"},"breadcrumb":{"@id":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/zodiac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test2.bolderparis.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Phone cases","item":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/"},{"@type":"ListItem","position":3,"name":"Clear cases","item":"https:\/\/test2.bolderparis.com\/product-category\/phone-cases\/clear-cases\/"},{"@type":"ListItem","position":4,"name":"Zodiac"}]},{"@type":"WebSite","@id":"https:\/\/test2.bolderparis.com\/#website","url":"https:\/\/test2.bolderparis.com\/","name":"test2.bolderparis.com","description":"only cute people wear kasey","publisher":{"@id":"https:\/\/test2.bolderparis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test2.bolderparis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test2.bolderparis.com\/#organization","name":"KASEY CASES","url":"https:\/\/test2.bolderparis.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/","url":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg","contentUrl":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg","width":620,"height":357,"caption":"KASEY CASES"},"image":{"@id":"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/kaseycases\/","https:\/\/www.tiktok.com\/@kaseycases"]}]}},"_links":{"self":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product_cat\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product_cat\/102"}],"wp:post_type":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product?product_cat=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}