{"id":3662,"date":"2024-09-08T15:14:58","date_gmt":"2024-09-08T13:14:58","guid":{"rendered":"https:\/\/test2.bolderparis.com\/product\/chaine-a-noeuds-noire\/"},"modified":"2024-11-26T00:03:13","modified_gmt":"2024-11-25T23:03:13","slug":"chaine-nounours-noir","status":"publish","type":"product","link":"https:\/\/test2.bolderparis.com\/fr\/produit\/chaine-nounours-noir\/","title":{"rendered":"Cha\u00eene Nounours noir"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&#8211; Motif de noeud, c\u0153ur, ours et de perles<br \/>\n&#8211; Peut \u00eatre ins\u00e9r\u00e9 sur le c\u00f4t\u00e9 de votre \u00e9tui de t\u00e9l\u00e9phone Kasey ou attach\u00e9 avec notre carte de sangle m\u00e9tallique solide dans le trou du chargeur<br \/>\n&#8211; Peut \u00e9galement \u00eatre utilis\u00e9 comme porte-cl\u00e9s ou accessoiris\u00e9 sur votre sac<br \/>\n&#8211; Crochet et carte de sangle inclus <\/p>\n<p>&#8211; Gardez \u00e0 l&rsquo;esprit que la carte de sangle ne peut \u00eatre utilis\u00e9e que sur les \u00e9tuis de t\u00e9l\u00e9phone \u00e0 couverture compl\u00e8te. <\/p>\n","protected":false},"featured_media":2870,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[161,91,112,94,89],"product_tag":[],"class_list":{"0":"post-3662","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-meilleures-ventes","7":"product_cat-chaines-pour-telephone","8":"product_cat-chaine-courte-en-perles","9":"product_cat-accessoires","10":"product_cat-voir-tous","11":"desktop-align-center","12":"tablet-align-center","13":"mobile-align-center","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cha\u00eene Nounours noir - test2.bolderparis.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cha\u00eene Nounours noir - test2.bolderparis.com\" \/>\n<meta property=\"og:description\" content=\"- Motif de noeud, c\u0153ur, ours et de perles  - Peut \u00eatre ins\u00e9r\u00e9 sur le c\u00f4t\u00e9 de votre \u00e9tui de t\u00e9l\u00e9phone Kasey ou attach\u00e9 avec notre carte de sangle m\u00e9tallique solide dans le trou du chargeur  - Peut \u00e9galement \u00eatre utilis\u00e9 comme porte-cl\u00e9s ou accessoiris\u00e9 sur votre sac  - Crochet et carte de sangle inclus   - Gardez \u00e0 l&#039;esprit que la carte de sangle ne peut \u00eatre utilis\u00e9e que sur les \u00e9tuis de t\u00e9l\u00e9phone \u00e0 couverture compl\u00e8te.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/\" \/>\n<meta property=\"og:site_name\" content=\"test2.bolderparis.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T23:03:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/\",\"url\":\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/\",\"name\":\"Cha\u00eene Nounours noir - test2.bolderparis.com\",\"isPartOf\":{\"@id\":\"https:\/\/test2.bolderparis.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg\",\"datePublished\":\"2024-09-08T13:14:58+00:00\",\"dateModified\":\"2024-11-25T23:03:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#primaryimage\",\"url\":\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg\",\"contentUrl\":\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/test2.bolderparis.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/test2.bolderparis.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cha\u00eene Nounours noir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test2.bolderparis.com\/#website\",\"url\":\"https:\/\/test2.bolderparis.com\/\",\"name\":\"test2.bolderparis.com\",\"description\":\"only cute people wear kasey\",\"publisher\":{\"@id\":\"https:\/\/test2.bolderparis.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test2.bolderparis.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/test2.bolderparis.com\/#organization\",\"name\":\"KASEY CASES\",\"url\":\"https:\/\/test2.bolderparis.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg\",\"contentUrl\":\"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg\",\"width\":620,\"height\":357,\"caption\":\"KASEY CASES\"},\"image\":{\"@id\":\"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/kaseycases\/\",\"https:\/\/www.tiktok.com\/@kaseycases\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cha\u00eene Nounours noir - test2.bolderparis.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/","og_locale":"fr_FR","og_type":"article","og_title":"Cha\u00eene Nounours noir - test2.bolderparis.com","og_description":"- Motif de noeud, c\u0153ur, ours et de perles  - Peut \u00eatre ins\u00e9r\u00e9 sur le c\u00f4t\u00e9 de votre \u00e9tui de t\u00e9l\u00e9phone Kasey ou attach\u00e9 avec notre carte de sangle m\u00e9tallique solide dans le trou du chargeur  - Peut \u00e9galement \u00eatre utilis\u00e9 comme porte-cl\u00e9s ou accessoiris\u00e9 sur votre sac  - Crochet et carte de sangle inclus   - Gardez \u00e0 l'esprit que la carte de sangle ne peut \u00eatre utilis\u00e9e que sur les \u00e9tuis de t\u00e9l\u00e9phone \u00e0 couverture compl\u00e8te.","og_url":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/","og_site_name":"test2.bolderparis.com","article_modified_time":"2024-11-25T23:03:13+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/","url":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/","name":"Cha\u00eene Nounours noir - test2.bolderparis.com","isPartOf":{"@id":"https:\/\/test2.bolderparis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#primaryimage"},"image":{"@id":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#primaryimage"},"thumbnailUrl":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg","datePublished":"2024-09-08T13:14:58+00:00","dateModified":"2024-11-25T23:03:13+00:00","breadcrumb":{"@id":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#primaryimage","url":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg","contentUrl":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/test2.bolderparis.com\/produit\/phone-chain-black-bear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test2.bolderparis.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/test2.bolderparis.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cha\u00eene Nounours noir"}]},{"@type":"WebSite","@id":"https:\/\/test2.bolderparis.com\/#website","url":"https:\/\/test2.bolderparis.com\/","name":"test2.bolderparis.com","description":"only cute people wear kasey","publisher":{"@id":"https:\/\/test2.bolderparis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test2.bolderparis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/test2.bolderparis.com\/#organization","name":"KASEY CASES","url":"https:\/\/test2.bolderparis.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/","url":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg","contentUrl":"https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2024\/07\/cropped-Logo-kasey-2.jpg","width":620,"height":357,"caption":"KASEY CASES"},"image":{"@id":"https:\/\/test2.bolderparis.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/kaseycases\/","https:\/\/www.tiktok.com\/@kaseycases"]}]}},"uagb_featured_image_src":{"full":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg",2000,2000,false],"thumbnail":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-300x300.jpg",300,300,true],"medium":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-360x360.jpg",360,360,true],"medium_large":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-768x768.jpg",768,768,true],"large":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-900x900.jpg",900,900,true],"1536x1536":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1.jpg",2000,2000,false],"product-search-thumbnail-32x32":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-32x32.jpg",32,32,true],"woocommerce_thumbnail":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-360x360.jpg",360,360,true],"woocommerce_single":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-900x900.jpg",900,900,true],"woocommerce_gallery_thumbnail":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-200x200.jpg",200,200,true],"variation_swatches_image_size":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-50x50.jpg",50,50,true],"variation_swatches_tooltip_size":["https:\/\/test2.bolderparis.com\/wp-content\/uploads\/2023\/12\/CHAINE-COURTE-NOEUDS-NOIR-NOUNOURS-1-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"test2.bolderparis.com","author_link":"https:\/\/test2.bolderparis.com\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"- Motif de noeud, c\u0153ur, ours et de perles - Peut \u00eatre ins\u00e9r\u00e9 sur le c\u00f4t\u00e9 de votre \u00e9tui de t\u00e9l\u00e9phone Kasey ou attach\u00e9 avec notre carte de sangle m\u00e9tallique solide dans le trou du chargeur - Peut \u00e9galement \u00eatre utilis\u00e9 comme porte-cl\u00e9s ou accessoiris\u00e9 sur votre sac - Crochet et carte de sangle inclus\u2026","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product\/3662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/comments?post=3662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/media\/2870"}],"wp:attachment":[{"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/media?parent=3662"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3662"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3662"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/test2.bolderparis.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}